{"id":2451,"date":"2024-06-30T20:19:40","date_gmt":"2024-06-30T18:19:40","guid":{"rendered":"https:\/\/www.raulmayoral.es\/?p=2451"},"modified":"2024-06-30T20:19:43","modified_gmt":"2024-06-30T18:19:43","slug":"29-de-junio-san-pedro-y-san-pablo-siglo-i","status":"publish","type":"post","link":"https:\/\/www.raulmayoral.es\/index.php\/2024\/06\/30\/29-de-junio-san-pedro-y-san-pablo-siglo-i\/","title":{"rendered":"29 de junio. San Pedro y San Pablo (siglo I)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las dos caras de la medalla de la Iglesia: el disc\u00edpulo y el converso, el hombre que vivi\u00f3 d\u00eda a d\u00eda con <strong>Cristo <\/strong>y el que solo le oy\u00f3 en la ceguera del camino de Damasco; el pescador y el intelectual, el jud\u00edo fiel a la tradici\u00f3n de sus mayores y el jud\u00edo abierto al universo entero; la llave y la espada, la piedra y el viento. Y en ambos la culpa, traici\u00f3n y persecuci\u00f3n, que reparar. Y los nombres distintos: <strong>Sim\u00f3n<\/strong>, <strong>Pedro<\/strong>, <strong>Saulo<\/strong>, <strong>Pablo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Qu\u00e9 extra\u00f1os fundamentos! La fidelidad del que fue d\u00e9bil en la prueba y el ardor proselitista del que hab\u00eda sido perseguidor. El que se entierra en Roma, piedra angular del edificio de la Iglesia, y el que esparce por el mundo el Evangelio para ir a morir a Roma. <strong>Pedro<\/strong> crucificado boca abajo por humildad, y <strong>Pablo<\/strong> haciendo el prodigio p\u00f3stumo con su cabeza reci\u00e9n cortada, que brinca tres veces sobre el suelo, incansable despu\u00e9s de la muerte y alumbrando tres fuentes. Ambos contribuyen a a la alegor\u00eda de la salvaci\u00f3n. Todo es alegor\u00eda y ambos forman las dos vertientes complementarias de la fe: permanecer en el arraigo y dispersarse para la multiplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>San Pedro<\/strong> y <strong>San Pablo<\/strong> ilustran as\u00ed la historia de la Iglesia con sus contrastes, incluso con sus divergencias, como su enfrentamiento en Antioqu\u00eda. \u00bfHay que hacerse jud\u00edos para ser cristianos? \u00c9sta es la cuesti\u00f3n que les enfrenta. Y entonces la amplitud de criterio de Pablo da nombre a su iglesia naciente: cat\u00f3lica, universal. Los hermanos se reconcilian en ellos, y en el calendario esta fraternidad en Cristo se sella en el mismo d\u00eda festivo, emparejados eternamente en la Gloria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <em>La casa de los Santos. Un Santo para cada d\u00eda<\/em>. Carlos Pujol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las dos caras de la medalla de la Iglesia: el disc\u00edpulo y el converso, el hombre que vivi\u00f3 d\u00eda a d\u00eda con Cristo y el que solo le oy\u00f3 en la ceguera del camino de Damasco; el pescador y el intelectual, el jud\u00edo fiel a la tradici\u00f3n de sus mayores y el jud\u00edo abierto al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2452,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[32],"tags":[],"class_list":["post-2451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-santoral"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.raulmayoral.es\/wp-content\/uploads\/2024\/06\/29-junio.jpg?fit=405%2C243&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.raulmayoral.es\/index.php\/wp-json\/wp\/v2\/posts\/2451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.raulmayoral.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.raulmayoral.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.raulmayoral.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.raulmayoral.es\/index.php\/wp-json\/wp\/v2\/comments?post=2451"}],"version-history":[{"count":2,"href":"https:\/\/www.raulmayoral.es\/index.php\/wp-json\/wp\/v2\/posts\/2451\/revisions"}],"predecessor-version":[{"id":2454,"href":"https:\/\/www.raulmayoral.es\/index.php\/wp-json\/wp\/v2\/posts\/2451\/revisions\/2454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.raulmayoral.es\/index.php\/wp-json\/wp\/v2\/media\/2452"}],"wp:attachment":[{"href":"https:\/\/www.raulmayoral.es\/index.php\/wp-json\/wp\/v2\/media?parent=2451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.raulmayoral.es\/index.php\/wp-json\/wp\/v2\/categories?post=2451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.raulmayoral.es\/index.php\/wp-json\/wp\/v2\/tags?post=2451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}